{"id":10862,"date":"2021-08-19T20:26:00","date_gmt":"2021-08-19T18:26:00","guid":{"rendered":"https:\/\/www.sartrouville-escalade.fr\/worexp\/?p=10862"},"modified":"2021-10-01T19:10:15","modified_gmt":"2021-10-01T17:10:15","slug":"renouvellement-des-voies-2","status":"publish","type":"post","link":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/2021\/08\/19\/renouvellement-des-voies-2\/","title":{"rendered":"RENOUVELLEMENT DES VOIES"},"content":{"rendered":"\n<p>Durant les vacances de no\u00ebl 2020, comme vous le savez, nous n&rsquo;avons malheureusement pas pu nettoyer et renouveler les voies. Nous avons exceptionnellement la possibilit\u00e9 de le faire en cette fin d&rsquo;\u00e9t\u00e9.<\/p>\n\n\n\n<p>Nous projetons ainsi, avec votre aide pr\u00e9cieuse, de retirer toutes les prises du mur, de les nettoyer sous haute pression et d&rsquo;ouvrir de nouvelles voies, ce qui permettra \u00e0 chacun une grimpe plus agr\u00e9able d\u00e8s la rentr\u00e9e.<\/p>\n\n\n\n<p>Pour cela nous avons besoin <strong>d&rsquo;un maximum de b\u00e9n\u00e9vole du 23 au 24<\/strong> <strong>ao\u00fbt<\/strong>. Cette fois, nous vous sollicitons uniquement pour le d\u00e9montage et le nettoyage. Plus nous serons nombreux plus ce sera rapide !<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Pour le d\u00e9montage en bas des voies tout le monde peut participer.<\/p>\n\n\n\n<p>Pour le nettoyage, le club poss\u00e8de un nettoyeur haute pression, il faut juste de la main d&rsquo;oeuvre motiv\u00e9e (avec des bottes c&rsquo;est mieux).<\/p>\n\n\n\n<p>Pour le d\u00e9montage du haut des voies, il faut bien s\u00fbr des grimpeurs autonomes ma\u00eetrisant la remont\u00e9e sur grigri, avec son propre mat\u00e9riel.<\/p>\n\n\n\n<p>Nous vous invitons \u00e0 remplir d\u00e8s maintenant le sondage ci-dessous afin de pouvoir mettre en oeuvre cette action : <\/p>\n\n\n\n<p><a href=\"https:\/\/framadate.org\/bD8fwNt4M6V4TKfs\">https:\/\/framadate.org\/bD8fwNt4M6V4TKfs<\/a><\/p>\n\n\n\n<p>Merci par avance de votre participation<\/p>\n\n\n\n<p>Le bureau<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant les vacances de no\u00ebl 2020, comme vous le savez, nous n&rsquo;avons malheureusement pas pu nettoyer et renouveler les voies. Nous avons exceptionnellement la possibilit\u00e9 de le faire en cette &hellip; <a href=\"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/2021\/08\/19\/renouvellement-des-voies-2\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">RENOUVELLEMENT DES VOIES<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":27,"featured_media":7039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[89,18],"tags":[],"class_list":["post-10862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-esprit-club","category-espritclub"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/10862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/comments?post=10862"}],"version-history":[{"count":5,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/10862\/revisions"}],"predecessor-version":[{"id":10867,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/10862\/revisions\/10867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/media\/7039"}],"wp:attachment":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/media?parent=10862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/categories?post=10862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/tags?post=10862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}