{"id":12421,"date":"2024-03-03T11:58:00","date_gmt":"2024-03-03T10:58:00","guid":{"rendered":"https:\/\/www.sartrouville-escalade.fr\/worexp\/?p=12421"},"modified":"2024-04-17T13:31:37","modified_gmt":"2024-04-17T11:31:37","slug":"challenge-des-yvelines-etape-sartrouvilloise-appel-aux-benevoles","status":"publish","type":"post","link":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/2024\/03\/03\/challenge-des-yvelines-etape-sartrouvilloise-appel-aux-benevoles\/","title":{"rendered":"Challenge des Yvelines : \u00e9tape Sartrouvilloise, appel aux b\u00e9n\u00e9voles."},"content":{"rendered":"\n<p>La section escalade organise l&rsquo;\u00e9tape Sartrouvilloise du challenge annuel des Yvelines pour les jeunes comp\u00e9titeurs du d\u00e9partement, microbes (U10), poussins (U12) et benjamins (U14)<strong>, le dimanche\u00a010 mars\u00a02024<\/strong> \u00e0 partir de 9h00, fin de la journ\u00e9e vers 17h.<\/p>\n\n\n\n<p>Pour assurer l&rsquo;organisation de cet \u00e9v\u00e9nement nous avons besoin de nombreux&nbsp;<strong>b\u00e9n\u00e9voles<\/strong>, licenci\u00e9s du club ou parents de licenci\u00e9s du club.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>L&rsquo;organisation est la suivante :<\/p>\n\n\n\n<p>&#8211; Pr\u00e9paration de la salle le samedi&nbsp;9 mars de 18h \u00e0 20h.<\/p>\n\n\n\n<p>Dimanche 10 mars :<\/p>\n\n\n\n<p>&#8211;&nbsp;10&nbsp;personnes&nbsp;(ayant au moins le passeport jaune) pour&nbsp;<strong>assurer<\/strong>&nbsp;les&nbsp;jeunes, de 9h \u00e0 12h30&nbsp;et\/ou 13h00&nbsp;\u00e0 16h30.<\/p>\n\n\n\n<p>&#8211;&nbsp;10&nbsp;personnes&nbsp;pour<strong>&nbsp;juger<\/strong>&nbsp;(bloc, voies de difficult\u00e9 ou de vitesse), les r\u00e8gles vous seront&nbsp;donn\u00e9es en d\u00e9but de comp\u00e9tition, cela reste tr\u00e8s simple, de&nbsp;9h \u00e0 12h30&nbsp;et\/ou 13h00&nbsp;\u00e0 16h30.<\/p>\n\n\n\n<p>&#8211; Environ&nbsp;6&nbsp;personnes&nbsp;pour tenir la&nbsp;<strong>buvette<\/strong>&nbsp;(passeport \u00ab\u00a0sourire et calme\u00a0\u00bb \ud83d\ude42 comme toujours dans le plus pur esprit club !&nbsp;de 9h \u00e0 13h et\/ou de 13h \u00e0 17h.<\/p>\n\n\n\n<p>&#8211; Vos propositions&nbsp;culinaires sucr\u00e9es ou sal\u00e9es qui seront mises&nbsp;en&nbsp;vente.<\/p>\n\n\n\n<p>Plus nous serons nombreux, plus nous pourrons nous relayer.<\/p>\n\n\n\n<p>Si vous pouvez contribuer d&rsquo;une fa\u00e7on ou d&rsquo;une autre le samedi soir, le dimanche matin et ou l&rsquo;apr\u00e8s midi, merci de renseigner le questionnaire ci-dessous, il suffit de cliquer&nbsp;sur la liste &#8211; \u00e0 choix multiple &#8211;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.sartrouville-escalade.fr\/questionnaire\/questionnaire.php\" data-type=\"link\" data-id=\"https:\/\/www.sartrouville-escalade.fr\/questionnaire\/benevoleschallengeyvelines2024\/index.html\">Questionnaire b\u00e9n\u00e9voles challenge yvelines 2024<\/a><\/p>\n\n\n\n<p>Pour toute question merci de contacter :<\/p>\n\n\n\n<p><a href=\"mailto:secretaire@sartrouville-escalade.fr\">secretaire@sartrouville-escalade.fr<\/a> et\/ou <a href=\"mailto:secretaire_adjoint@sartrouville-escalade.fr\">secretaire_adjoint@sartrouville-escalade.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La section escalade organise l&rsquo;\u00e9tape Sartrouvilloise du challenge annuel des Yvelines pour les jeunes comp\u00e9titeurs du d\u00e9partement, microbes (U10), poussins (U12) et benjamins (U14), le dimanche\u00a010 mars\u00a02024 \u00e0 partir de &hellip; <a href=\"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/2024\/03\/03\/challenge-des-yvelines-etape-sartrouvilloise-appel-aux-benevoles\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Challenge des Yvelines : \u00e9tape Sartrouvilloise, appel aux b\u00e9n\u00e9voles.<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":27,"featured_media":12427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[87],"tags":[],"class_list":["post-12421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-competitions"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/12421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/comments?post=12421"}],"version-history":[{"count":3,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/12421\/revisions"}],"predecessor-version":[{"id":12428,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/posts\/12421\/revisions\/12428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/media\/12427"}],"wp:attachment":[{"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/media?parent=12421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/categories?post=12421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sartrouville-escalade.fr\/worexp\/index.php\/wp-json\/wp\/v2\/tags?post=12421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}